{"id":7123,"date":"2025-12-17T11:21:54","date_gmt":"2025-12-17T10:21:54","guid":{"rendered":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/?p=7123"},"modified":"2025-12-17T11:25:38","modified_gmt":"2025-12-17T10:25:38","slug":"la-biblioteca-san-julian-os-desea-unas-felices-fiestas-%f0%9f%8e%84%f0%9f%93%9a%e2%9c%a8","status":"publish","type":"post","link":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/la-biblioteca-san-julian-os-desea-unas-felices-fiestas-%f0%9f%8e%84%f0%9f%93%9a%e2%9c%a8\/","title":{"rendered":"La Biblioteca San Juli\u00e1n os desea unas Felices Fiestas \ud83c\udf84\ud83d\udcda\u2728"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian-1024x768.jpg\" alt=\"\" class=\"wp-image-7124\" srcset=\"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian-1024x768.jpg 1024w, http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian-300x225.jpg 300w, http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian-768x576.jpg 768w, http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian-1536x1152.jpg 1536w, http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian-150x113.jpg 150w, http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian-24x18.jpg 24w, http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian-36x27.jpg 36w, http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian-48x36.jpg 48w, http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/uploads\/2025\/12\/Belen-Bca-San-Julian.jpg 2016w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p style=\"font-size:30px\">\ud83c\udf84\ud83d\udcda Desde la <strong>Biblioteca San Juli\u00e1n<\/strong> os deseamos unas <strong>Felices Fiestas<\/strong> \u2728<br>Gracias por acompa\u00f1arnos durante todo el a\u00f1o y por hacer de la biblioteca un espacio vivo y cercano \ud83d\udc99<br>Os esperamos con nuevas lecturas, actividades y muchas historias por descubrir \ud83d\udcd6\ud83c\udf81<\/p>\n\n\n\n<p style=\"font-size:30px\">\u00a1Feliz Navidad y pr\u00f3spero a\u00f1o 2026! \ud83c\udf84\u2728<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><\/p>\n<div class=\"addtoany_share_save_container\"><div class=\"a2a_kit a2a_target addtoany_list\" id=\"wpa2a_1\"><a class=\"a2a_dd addtoany_share_save\" href=\"http:\/\/www.addtoany.com\/share_save\"><img src=\"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/plugins\/add-to-any\/share_save_171_16.png\" width=\"171\" height=\"16\" alt=\"Share\"\/><\/a><\/div>\n<script type=\"text\/javascript\"><!--\nwpa2a.script_load();\n\/\/--><\/script>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf84\ud83d\udcda Desde la Biblioteca San Juli\u00e1n os deseamos unas Felices Fiestas \u2728Gracias por acompa\u00f1arnos durante todo el a\u00f1o y por hacer de la biblioteca un espacio vivo y cercano \ud83d\udc99Os esperamos con nuevas lecturas, actividades y muchas historias por descubrir \ud83d\udcd6\ud83c\udf81 \u00a1Feliz Navidad y pr\u00f3spero a\u00f1o 2026! \ud83c\udf84\u2728<\/p>\n<div class=\"addtoany_share_save_container\"><div class=\"a2a_kit a2a_target addtoany_list\" id=\"wpa2a_2\"><a class=\"a2a_dd addtoany_share_save\" href=\"http:\/\/www.addtoany.com\/share_save\"><img src=\"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-content\/plugins\/add-to-any\/share_save_171_16.png\" width=\"171\" height=\"16\" alt=\"Share\"\/><\/a><\/div><\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[111,183],"_links":{"self":[{"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/posts\/7123"}],"collection":[{"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/comments?post=7123"}],"version-history":[{"count":2,"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/posts\/7123\/revisions"}],"predecessor-version":[{"id":7127,"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/posts\/7123\/revisions\/7127"}],"wp:attachment":[{"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/media?parent=7123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/categories?post=7123"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rmbs.es\/blog\/biblioteca-san-julian\/wp-json\/wp\/v2\/tags?post=7123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}